{"id":387,"date":"2016-12-03T13:38:40","date_gmt":"2016-12-03T15:38:40","guid":{"rendered":"https:\/\/www.ipessp.edu.br\/site\/?post_type=cursos&#038;p=387"},"modified":"2025-10-23T20:01:17","modified_gmt":"2025-10-23T23:01:17","slug":"analises-clinicas-veterinaria","status":"publish","type":"cursos","link":"https:\/\/ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/","title":{"rendered":"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Na\u00a0P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria<\/strong><\/span> do IPESSP, os alunos adquirem s\u00f3lida base te\u00f3rica e pr\u00e1tica do conte\u00fado program\u00e1tico, de forma aprofundada e atualizada. Nas aulas pr\u00e1ticas, s\u00e3o fornecidos subs\u00eddios para a resolu\u00e7\u00e3o de casos cl\u00ednicos, a partir de exames de diagn\u00f3stico.<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #800000;\"><em>Trata-se de um dos poucos cursos no Brasil que aborda aspectos <strong>end\u00f3crinos<\/strong> e <strong>oncol\u00f3gicos<\/strong> na grade curricular.<\/em><\/span><\/h4>\n<p style=\"text-align: justify;\">Os docentes s\u00e3o<span style=\"color: #800000;\"><strong> Mestres e Doutores<\/strong> <\/span>com atua\u00e7\u00e3o em Hospitais, Cl\u00ednicas e laborat\u00f3rios.<\/p>\n<p style=\"text-align: justify;\">Com\u00a0 parceria com o Dr Vet. Hospital Veterin\u00e1rio permite aos alunos fazer est\u00e1gios, aulas pr\u00e1ticas e visitas t\u00e9cnicas.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m conhecer aspectos pr\u00e1ticos diretos do cotidiano laboratorial, a P\u00f3s An\u00e1lises Cl\u00ednicas Veterin\u00e1ria proporciona ao aluno network com os profissionais de excel\u00eancia que ministraram o conte\u00fado e colegas, ampliando as perspectivas e oportunidades no mercado de trabalho.<\/p>\n<p>obrigat\u00f3rio o aluno a ter todas as vacinas contra hepatite B, dupla adulto (difteria e t\u00e9tano), febre amarela e triviral (sarampo, rub\u00e9ola e caxumba).<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #a81818;\"><span style=\"color: #800000;\">P\u00fablico-alvo:<\/span><strong><span style=\"color: #333333;\"> Profissionais com gradua\u00e7\u00e3o em Ci\u00eancias Biol\u00f3gicas, Biomedicina, Bioqu\u00edmica, Farm\u00e1cia Bioqu\u00edmica, Medicina e Medicina Veterin\u00e1ria obtidos em curso reconhecido pelo Conselho Nacional de Educa\u00e7\u00e3o (CNE)<\/span><\/strong><\/span><\/h5>\n<p>A Faculdade IPESSP segue as normas do CNE\/MEC, n\u00e3o se responsabiliza por nenhuma decis\u00e3o de habilita\u00e7\u00f5es dos Conselhos Regionais e Federais.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria do IPESSP, os alunos adquirem s\u00f3lida base te\u00f3rica e pr\u00e1tica do conte\u00fado program\u00e1tico, de forma aprofundada e atualizada. Nas aulas pr\u00e1ticas, s\u00e3o fornecidos subs\u00eddios para a resolu\u00e7\u00e3o de casos cl\u00ednicos, a partir de exames de diagn\u00f3stico.<\/p>\n","protected":false},"author":19,"featured_media":61986,"template":"","c_cursos":[22],"sc_cursos":[166,172],"class_list":["post-387","cursos","type-cursos","status-publish","has-post-thumbnail","hentry","c_cursos-pos-graduacao","sc_cursos-pos-graduacao","sc_cursos-veterinaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP<\/title>\n<meta name=\"description\" content=\"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP\" \/>\n<meta property=\"og:description\" content=\"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/\" \/>\n<meta property=\"og:site_name\" content=\"IPESSP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T23:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/12\/rsrssr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ipessp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/\",\"url\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/\",\"name\":\"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/rsrssr.jpg\",\"datePublished\":\"2016-12-03T15:38:40+00:00\",\"dateModified\":\"2025-10-23T23:01:17+00:00\",\"description\":\"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/rsrssr.jpg\",\"contentUrl\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/rsrssr.jpg\",\"width\":799,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/cursos\\\/analises-clinicas-veterinaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cursos\",\"item\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/cursos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\",\"name\":\"IPESSP\",\"description\":\"Instituto de Pesquisa e Educa\u00e7\u00e3o em Sa\u00fade de S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#organization\",\"name\":\"IPESSP\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logotipo.png\",\"contentUrl\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logotipo.png\",\"width\":900,\"height\":462,\"caption\":\"IPESSP\"},\"image\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ipesspedu\\\/?ref=pages_you_manage\",\"https:\\\/\\\/x.com\\\/ipessp\",\"https:\\\/\\\/www.instagram.com\\\/ipessp\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/watch?v=mlwRSWmfisw&amp;t=93s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP","description":"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/","og_locale":"pt_BR","og_type":"article","og_title":"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP","og_description":"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.","og_url":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/","og_site_name":"IPESSP","article_publisher":"https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage","article_modified_time":"2025-10-23T23:01:17+00:00","og_image":[{"width":799,"height":570,"url":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/12\/rsrssr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ipessp","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/","url":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/","name":"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria - IPESSP","isPartOf":{"@id":"https:\/\/ipessp.edu.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/#primaryimage"},"image":{"@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/#primaryimage"},"thumbnailUrl":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2016\/12\/rsrssr.jpg","datePublished":"2016-12-03T15:38:40+00:00","dateModified":"2025-10-23T23:01:17+00:00","description":"A P\u00f3s-gradua\u00e7\u00e3o em An\u00e1lises Cl\u00ednicas Veterin\u00e1ria amplia e atualiza o conhecimento em procedimentos anal\u00edticos em animais de cria\u00e7\u00e3o e de experimenta\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/#primaryimage","url":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2016\/12\/rsrssr.jpg","contentUrl":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2016\/12\/rsrssr.jpg","width":799,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipessp.edu.br\/site\/cursos\/analises-clinicas-veterinaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ipessp.edu.br\/site\/"},{"@type":"ListItem","position":2,"name":"Cursos","item":"https:\/\/ipessp.edu.br\/site\/cursos\/"},{"@type":"ListItem","position":3,"name":"An\u00e1lises Cl\u00ednicas Veterin\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/ipessp.edu.br\/site\/#website","url":"https:\/\/ipessp.edu.br\/site\/","name":"IPESSP","description":"Instituto de Pesquisa e Educa\u00e7\u00e3o em Sa\u00fade de S\u00e3o Paulo","publisher":{"@id":"https:\/\/ipessp.edu.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ipessp.edu.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ipessp.edu.br\/site\/#organization","name":"IPESSP","url":"https:\/\/ipessp.edu.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ipessp.edu.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/10\/logotipo.png","contentUrl":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/10\/logotipo.png","width":900,"height":462,"caption":"IPESSP"},"image":{"@id":"https:\/\/ipessp.edu.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage","https:\/\/x.com\/ipessp","https:\/\/www.instagram.com\/ipessp\/","https:\/\/www.linkedin.com\/feed\/","https:\/\/www.youtube.com\/watch?v=mlwRSWmfisw&amp;t=93s"]}]}},"_links":{"self":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/cursos\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/cursos"}],"about":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/types\/cursos"}],"author":[{"embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/users\/19"}],"version-history":[{"count":133,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/cursos\/387\/revisions"}],"predecessor-version":[{"id":63536,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/cursos\/387\/revisions\/63536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/media\/61986"}],"wp:attachment":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/media?parent=387"}],"wp:term":[{"taxonomy":"c_cursos","embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/c_cursos?post=387"},{"taxonomy":"sc_cursos","embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/sc_cursos?post=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}