{"id":579,"date":"2017-02-21T10:10:40","date_gmt":"2017-02-21T13:10:40","guid":{"rendered":"https:\/\/www.ipessp.edu.br\/site\/?post_type=depoimentos&#038;p=579"},"modified":"2018-06-06T16:00:08","modified_gmt":"2018-06-06T19:00:08","slug":"sheila-menegati-depoimento-ipessp","status":"publish","type":"depoimentos","link":"https:\/\/ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/","title":{"rendered":"Sheila Menegati"},"content":{"rendered":"<p style=\"text-align: center;\">&#8220;Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu, nas disciplinas de Hematologia, Banco de Sangue e\u00a0Administra\u00e7\u00e3o Laboratorial. Hoje, sou supervisora de est\u00e1gio, nos cursos de Farm\u00e1cia e Biomedicina&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada a ser docente no CEUNSP, em Itu.<\/p>\n","protected":false},"author":19,"featured_media":643,"template":"","class_list":["post-579","depoimentos","type-depoimentos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP<\/title>\n<meta name=\"description\" content=\"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/\" \/>\n<meta property=\"og:site_name\" content=\"IPESSP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-06T19:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2017\/02\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ipessp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/\",\"url\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/\",\"name\":\"Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg\",\"datePublished\":\"2017-02-21T13:10:40+00:00\",\"dateModified\":\"2018-06-06T19:00:08+00:00\",\"description\":\"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg\",\"contentUrl\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg\",\"width\":200,\"height\":200,\"caption\":\"Foto Sheila Menegati\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/depoimentos\\\/sheila-menegati-depoimento-ipessp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Depoimentos\",\"item\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/depoimentos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sheila Menegati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\",\"name\":\"IPESSP\",\"description\":\"Instituto de Pesquisa e Educa\u00e7\u00e3o em Sa\u00fade de S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#organization\",\"name\":\"IPESSP\",\"url\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logotipo.png\",\"contentUrl\":\"https:\\\/\\\/www.ipessp.edu.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logotipo.png\",\"width\":900,\"height\":462,\"caption\":\"IPESSP\"},\"image\":{\"@id\":\"https:\\\/\\\/ipessp.edu.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ipesspedu\\\/?ref=pages_you_manage\",\"https:\\\/\\\/x.com\\\/ipessp\",\"https:\\\/\\\/www.instagram.com\\\/ipessp\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/feed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/watch?v=mlwRSWmfisw&amp;t=93s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP","description":"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/","og_locale":"pt_BR","og_type":"article","og_title":"Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP","og_description":"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.","og_url":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/","og_site_name":"IPESSP","article_publisher":"https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage","article_modified_time":"2018-06-06T19:00:08+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2017\/02\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ipessp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/","url":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/","name":"Depoimento Sheila Menegati sobre os cursos de p\u00f3s-gradua\u00e7\u00e3o IPESSP","isPartOf":{"@id":"https:\/\/ipessp.edu.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/#primaryimage"},"image":{"@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/#primaryimage"},"thumbnailUrl":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2017\/02\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg","datePublished":"2017-02-21T13:10:40+00:00","dateModified":"2018-06-06T19:00:08+00:00","description":"Ap\u00f3s me tornar especialista em Hematologia Laboratorial e Hemoterapia pelo IPESSP fui convidada para ser docente no CEUNSP, em Itu.","breadcrumb":{"@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/#primaryimage","url":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2017\/02\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg","contentUrl":"https:\/\/ipessp.edu.br\/site\/wp-content\/uploads\/2017\/02\/SHEILA-MENEGATI_-TESTEMUNHOS.jpg","width":200,"height":200,"caption":"Foto Sheila Menegati"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipessp.edu.br\/site\/depoimentos\/sheila-menegati-depoimento-ipessp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ipessp.edu.br\/site\/"},{"@type":"ListItem","position":2,"name":"Depoimentos","item":"https:\/\/ipessp.edu.br\/site\/depoimentos\/"},{"@type":"ListItem","position":3,"name":"Sheila Menegati"}]},{"@type":"WebSite","@id":"https:\/\/ipessp.edu.br\/site\/#website","url":"https:\/\/ipessp.edu.br\/site\/","name":"IPESSP","description":"Instituto de Pesquisa e Educa\u00e7\u00e3o em Sa\u00fade de S\u00e3o Paulo","publisher":{"@id":"https:\/\/ipessp.edu.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ipessp.edu.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ipessp.edu.br\/site\/#organization","name":"IPESSP","url":"https:\/\/ipessp.edu.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ipessp.edu.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/10\/logotipo.png","contentUrl":"https:\/\/www.ipessp.edu.br\/site\/wp-content\/uploads\/2016\/10\/logotipo.png","width":900,"height":462,"caption":"IPESSP"},"image":{"@id":"https:\/\/ipessp.edu.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ipesspedu\/?ref=pages_you_manage","https:\/\/x.com\/ipessp","https:\/\/www.instagram.com\/ipessp\/","https:\/\/www.linkedin.com\/feed\/","https:\/\/www.youtube.com\/watch?v=mlwRSWmfisw&amp;t=93s"]}]}},"_links":{"self":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/depoimentos\/579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/depoimentos"}],"about":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/types\/depoimentos"}],"author":[{"embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/users\/19"}],"version-history":[{"count":0,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/depoimentos\/579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/media\/643"}],"wp:attachment":[{"href":"https:\/\/ipessp.edu.br\/site\/wp-json\/wp\/v2\/media?parent=579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}